{"id":196,"date":"2023-05-25T16:49:08","date_gmt":"2023-05-25T14:49:08","guid":{"rendered":"https:\/\/www.laforneria.it\/b2b\/?post_type=product&#038;p=196"},"modified":"2026-03-05T12:12:25","modified_gmt":"2026-03-05T11:12:25","slug":"panettone-alle-ciliegie-750-g-cartone-da-6pz","status":"publish","type":"product","link":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/","title":{"rendered":"Panettone alle Ciliegie 750 g &#8211; 1 cartone da 6 Pz &#8211;"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Per i nostri prodotti utilizziamo solo materie prime di qualit\u00e0<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;center&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221;][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;177&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Solo farina selezionata e certificata<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;170&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Burro concentrato bretone, ottenuto esclusivamente da latte fresco vaccino<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;183&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Solo uova di allevamenti italiani<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;center&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221;][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;179&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Lo stesso lievito madre che utilizziamo da 50 anni per una qualit\u00e0 sempre costante<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;175&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Ciliegie intere denocciolate<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675933688386{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221; z_index=&#8221;&#8221; side_padding=&#8221;0%&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Cosa rende il nostro Panettone artigianale cosi unico?<\/h2>\n<p>[\/vc_column_text][vc_column_text]L&#8217;esperienza maturata nel tempo, la qualit\u00e0 e la genuinit\u00e0 delle materie prime selezionate ed il lievito madre di oltre 50 anni che viene rinfrescato tutti i giorni con passione dai nostri maestri pasticceri ci permettono di produrre un panettone artigianale di qualit\u00e0, equilibrato e genuino secondo la pi\u00f9 antica tradizione.[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;185&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675933688386{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221; z_index=&#8221;&#8221; side_padding=&#8221;0%&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Le fasi di produzione sono le stesse dal 1967<\/h2>\n<p>[\/vc_column_text][vc_column_text]1. Tre fasi di impasto con una lunga lievitazione naturale di oltre 30 ore.<br \/>\n2. Una lenta asciugatura naturale di 12 ore per mantenere inalterati i profumi, i sapori e la morbidezza caratteristici<br \/>\n3. Una lavorazione complessiva di oltre 3 giorni[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;184&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675934022179{padding-top: 50px !important;padding-bottom: 80px !important;}&#8221; z_index=&#8221;&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Tutti i nostri panettoni sono confezionati singolarmente a mano, in questo modo nella parte superiore dell&#8217;astuccio si forma il &#8220;fiore&#8221; caratteristica unica delle nostre confezioni.<\/p>\n<p style=\"text-align: center;\">I nostri prodotti NON contengono conservanti, coloranti, OGM, grassi idrogenati, olio di palma e<strong>\u00a0LATTOSIO<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 20pt;\"><strong>BONTA&#8217; DI PULA DAL 1967<\/strong><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Panettone artigianale con ciliegie intere denocciolate.<\/p>\n<p>Il nostro panettone artigianale alle ciliegie si caratterizza per un impasto soffice e morbido di un colore giallo tenue ed un profumo di ciliegie, uova, burro, vaniglia e zucchero.<\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Senza LATTOSIO<\/strong><\/span><\/p>\n<p>Peso: 750 g<\/p>\n<p><strong>Vendita min. 1 Cartone (6pz per cartone)<\/strong><\/p>\n<p><strong>Indica il numero di cartoni:<\/strong><\/p>\n","protected":false},"featured_media":750,"template":"","meta":[],"product_brand":[],"product_cat":[34,18],"product_tag":[],"class_list":{"0":"post-196","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-panettoni","7":"product_cat-senza-lattosio","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Panettone alle Ciliegie 750 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panettone alle Ciliegie 750 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B\" \/>\n<meta property=\"og:description\" content=\"Panettone artigianale con ciliegie intere denocciolate.  Il nostro panettone artigianale alle ciliegie si caratterizza per un impasto soffice e morbido di un colore giallo tenue ed un profumo di ciliegie, uova, burro, vaniglia e zucchero.  Senza LATTOSIO  Peso: 750 g  Vendita min. 1 Cartone (6pz per cartone)  Indica il numero di cartoni:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/\" \/>\n<meta property=\"og:site_name\" content=\"la Forneria di Pula Shop B2B\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T11:12:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/ciliegie-forneria-pula.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/\",\"name\":\"Panettone alle Ciliegie 750 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B\",\"isPartOf\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/ciliegie-forneria-pula.jpg\",\"datePublished\":\"2023-05-25T14:49:08+00:00\",\"dateModified\":\"2026-03-05T11:12:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#primaryimage\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/ciliegie-forneria-pula.jpg\",\"contentUrl\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/ciliegie-forneria-pula.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.laforneria.it\/b2b\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.laforneria.it\/b2b\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Panettone alle Ciliegie 750 g &#8211; 1 cartone da 6 Pz &#8211;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/#website\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/\",\"name\":\"la Forneria di Pula Shop B2B\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.laforneria.it\/b2b\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panettone alle Ciliegie 750 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/","og_locale":"it_IT","og_type":"article","og_title":"Panettone alle Ciliegie 750 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B","og_description":"Panettone artigianale con ciliegie intere denocciolate.  Il nostro panettone artigianale alle ciliegie si caratterizza per un impasto soffice e morbido di un colore giallo tenue ed un profumo di ciliegie, uova, burro, vaniglia e zucchero.  Senza LATTOSIO  Peso: 750 g  Vendita min. 1 Cartone (6pz per cartone)  Indica il numero di cartoni:","og_url":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/","og_site_name":"la Forneria di Pula Shop B2B","article_modified_time":"2026-03-05T11:12:25+00:00","og_image":[{"width":1000,"height":1000,"url":"http:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/ciliegie-forneria-pula.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/","url":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/","name":"Panettone alle Ciliegie 750 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B","isPartOf":{"@id":"https:\/\/www.laforneria.it\/b2b\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#primaryimage"},"image":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/ciliegie-forneria-pula.jpg","datePublished":"2023-05-25T14:49:08+00:00","dateModified":"2026-03-05T11:12:25+00:00","breadcrumb":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#primaryimage","url":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/ciliegie-forneria-pula.jpg","contentUrl":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/ciliegie-forneria-pula.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/panettone-alle-ciliegie-750-g-cartone-da-6pz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.laforneria.it\/b2b\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.laforneria.it\/b2b\/negozio\/"},{"@type":"ListItem","position":3,"name":"Panettone alle Ciliegie 750 g &#8211; 1 cartone da 6 Pz &#8211;"}]},{"@type":"WebSite","@id":"https:\/\/www.laforneria.it\/b2b\/#website","url":"https:\/\/www.laforneria.it\/b2b\/","name":"la Forneria di Pula Shop B2B","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laforneria.it\/b2b\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/media\/750"}],"wp:attachment":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/media?parent=196"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_brand?post=196"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_cat?post=196"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_tag?post=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}