{"id":246,"date":"2023-05-26T10:34:36","date_gmt":"2023-05-26T08:34:36","guid":{"rendered":"https:\/\/www.laforneria.it\/b2b\/?post_type=product&#038;p=246"},"modified":"2026-03-31T09:28:25","modified_gmt":"2026-03-31T07:28:25","slug":"colomba-classica-mandorlata-750-g-cartone-da-6pz","status":"publish","type":"product","link":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/","title":{"rendered":"Colomba Classica Mandorlata 750 g in Astuccio &#8211; 1 cartone da 5 Pz"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Per i nostri prodotti utilizziamo solo materie prime di qualit\u00e0<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;center&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221;][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;177&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Solo farina selezionata e certificata<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;170&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Burro concentrato bretone, ottenuto esclusivamente da latte fresco vaccino<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;183&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Solo uova di allevamenti italiani<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;center&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221;][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;179&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Lo stesso lievito madre che utilizziamo da 50 anni per una qualit\u00e0 sempre costante<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;178&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Mandorle intere pelate<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_single_image image=&#8221;182&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Scorze di arancia candita<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675933688386{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221; z_index=&#8221;&#8221; side_padding=&#8221;0%&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Cosa rende la nostra Colomba artigianale cosi unica?<\/h2>\n<p>[\/vc_column_text][vc_column_text]L&#8217;esperienza maturata nel tempo, la qualit\u00e0 e la genuinit\u00e0 delle materie prime selezionate ed il lievito madre di oltre 50 anni che viene rinfrescato tutti i giorni con passione dai nostri maestri pasticceri ci permettono di produrre un panettone artigianale di qualit\u00e0, equilibrato e genuino secondo la pi\u00f9 antica tradizione.[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;261&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675933688386{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221; z_index=&#8221;&#8221; side_padding=&#8221;0%&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Le fasi di produzione sono le stesse dal 1967<\/h2>\n<p>[\/vc_column_text][vc_column_text]1. Tre fasi di impasto con una lunga lievitazione naturale di oltre 30 ore.<br \/>\n2. Una lenta asciugatura naturale di 12 ore per mantenere inalterati i profumi, i sapori e la morbidezza caratteristici<br \/>\n3. Una lavorazione complessiva di oltre 3 giorni[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;184&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675934022179{padding-top: 50px !important;padding-bottom: 80px !important;}&#8221; z_index=&#8221;&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Tutte le nostre Colombe artigianali sono confezionati singolarmente a mano e con una confezione 100% riciclabile.<\/p>\n<p style=\"text-align: center;\">I nostri prodotti NON contengono conservanti, coloranti, OGM, grassi idrogenati, olio di palma e<strong>\u00a0LATTOSIO<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 20pt;\"><strong>BONTA&#8217; DI PULA DAL 1967<\/strong><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: 12pt;\">Colomba artigianale classica con uvetta e scorza di arancia fresca candita, guarnita con glassa, zucchero in granella e mandorle pelate.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\">La nostra colomba artigianale classica si caratterizza per un impasto soffice e morbido, di un colore giallo intenso ed un profumo di uova, burro, agrumi, vaniglia e zucchero.<\/span><\/p>\n<p><strong>SENZA LATTOSIO<\/strong><\/p>\n<p>Peso: 750 g<\/p>\n<p><strong>Vendita min. 1 Cartone (5pz per cartone)<\/strong><\/p>\n<p><strong>Indica il numero di cartoni:<\/strong><\/p>\n","protected":false},"featured_media":458,"template":"","meta":[],"product_brand":[],"product_cat":[17,18],"product_tag":[],"class_list":{"0":"post-246","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-colombe","7":"product_cat-senza-lattosio","9":"first","10":"outofstock","11":"featured","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Colomba Classica Mandorlata 750 g in Astuccio - 1 cartone da 5 Pz - la Forneria di Pula Shop B2B<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colomba Classica Mandorlata 750 g in Astuccio - 1 cartone da 5 Pz - la Forneria di Pula Shop B2B\" \/>\n<meta property=\"og:description\" content=\"Colomba artigianale classica con uvetta e scorza di arancia fresca candita, guarnita con glassa, zucchero in granella e mandorle pelate.  La nostra colomba artigianale classica si caratterizza per un impasto soffice e morbido, di un colore giallo intenso ed un profumo di uova, burro, agrumi, vaniglia e zucchero.  SENZA LATTOSIO  Peso: 750 g  Vendita min. 1 Cartone (5pz per cartone)  Indica il numero di cartoni:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/\" \/>\n<meta property=\"og:site_name\" content=\"la Forneria di Pula Shop B2B\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T07:28:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/CLASSICA-4-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/\",\"name\":\"Colomba Classica Mandorlata 750 g in Astuccio - 1 cartone da 5 Pz - la Forneria di Pula Shop B2B\",\"isPartOf\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/CLASSICA-4.png\",\"datePublished\":\"2023-05-26T08:34:36+00:00\",\"dateModified\":\"2026-03-31T07:28:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#primaryimage\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/CLASSICA-4.png\",\"contentUrl\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/CLASSICA-4.png\",\"width\":3168,\"height\":3168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.laforneria.it\/b2b\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.laforneria.it\/b2b\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Colomba Classica Mandorlata 750 g in Astuccio &#8211; 1 cartone da 5 Pz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/#website\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/\",\"name\":\"la Forneria di Pula Shop B2B\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.laforneria.it\/b2b\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colomba Classica Mandorlata 750 g in Astuccio - 1 cartone da 5 Pz - la Forneria di Pula Shop B2B","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/","og_locale":"it_IT","og_type":"article","og_title":"Colomba Classica Mandorlata 750 g in Astuccio - 1 cartone da 5 Pz - la Forneria di Pula Shop B2B","og_description":"Colomba artigianale classica con uvetta e scorza di arancia fresca candita, guarnita con glassa, zucchero in granella e mandorle pelate.  La nostra colomba artigianale classica si caratterizza per un impasto soffice e morbido, di un colore giallo intenso ed un profumo di uova, burro, agrumi, vaniglia e zucchero.  SENZA LATTOSIO  Peso: 750 g  Vendita min. 1 Cartone (5pz per cartone)  Indica il numero di cartoni:","og_url":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/","og_site_name":"la Forneria di Pula Shop B2B","article_modified_time":"2026-03-31T07:28:25+00:00","og_image":[{"width":1024,"height":1024,"url":"http:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/CLASSICA-4-1024x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/","url":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/","name":"Colomba Classica Mandorlata 750 g in Astuccio - 1 cartone da 5 Pz - la Forneria di Pula Shop B2B","isPartOf":{"@id":"https:\/\/www.laforneria.it\/b2b\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#primaryimage"},"image":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/CLASSICA-4.png","datePublished":"2023-05-26T08:34:36+00:00","dateModified":"2026-03-31T07:28:25+00:00","breadcrumb":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#primaryimage","url":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/CLASSICA-4.png","contentUrl":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/CLASSICA-4.png","width":3168,"height":3168},{"@type":"BreadcrumbList","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/colomba-classica-mandorlata-750-g-cartone-da-6pz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.laforneria.it\/b2b\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.laforneria.it\/b2b\/negozio\/"},{"@type":"ListItem","position":3,"name":"Colomba Classica Mandorlata 750 g in Astuccio &#8211; 1 cartone da 5 Pz"}]},{"@type":"WebSite","@id":"https:\/\/www.laforneria.it\/b2b\/#website","url":"https:\/\/www.laforneria.it\/b2b\/","name":"la Forneria di Pula Shop B2B","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laforneria.it\/b2b\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product\/246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/media\/458"}],"wp:attachment":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/media?parent=246"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_brand?post=246"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_cat?post=246"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_tag?post=246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}