{"id":318,"date":"2023-05-26T12:15:20","date_gmt":"2023-05-26T10:15:20","guid":{"rendered":"https:\/\/www.laforneria.it\/b2b\/?post_type=product&#038;p=318"},"modified":"2026-03-05T11:58:42","modified_gmt":"2026-03-05T10:58:42","slug":"pandoro-tradizionale-in-vasocottura","status":"publish","type":"product","link":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/","title":{"rendered":"Pandoro in Vasocottura 200 g &#8211; 1 cartone da 6 Pz &#8211;"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]<\/p>\n<h3 style=\"color: #000;\">Tramite la vasocottura, i nostri pandori vengono posizionati e cotti all&#8217;interno dei vasetti di vetro, ed una volta pronti vengono sfornati, chiusi col coperchio ermetico ed infine capovolti.<\/h3>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>Una volta aperto l&#8217;umidit\u00e0, la sofficit\u00e0, gli aromi ed i sapori sono come quelli di un pandoro appena sfornato.<\/h4>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Per i nostri prodotti utilizziamo solo materie prime di qualit\u00e0<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;center&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;177&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Solo farina selezionata e certificata<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;170&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Burro concentrato bretone, ottenuto esclusivamente da latte fresco vaccino<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;183&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Solo uova di allevamenti italiani<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;179&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Lo stesso lievito madre che utilizziamo da 50 anni per una qualit\u00e0 sempre costante<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675933688386{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221; z_index=&#8221;&#8221; side_padding=&#8221;0%&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Cosa rende il nostro Pandoro artigianale cosi unico?<\/h2>\n<p>[\/vc_column_text][vc_column_text]L&#8217;esperienza maturata nel tempo, la qualit\u00e0 e la genuinit\u00e0 delle materie prime selezionate ed il lievito madre di oltre 50 anni che viene rinfrescato tutti i giorni con passione dai nostri maestri pasticceri ci permettono di produrre un panettone artigianale di qualit\u00e0, equilibrato e genuino secondo la pi\u00f9 antica tradizione.[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;200&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675933688386{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221; z_index=&#8221;&#8221; side_padding=&#8221;0%&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Le fasi di produzione sono le stesse dal 1967<\/h2>\n<p>[\/vc_column_text][vc_column_text]1. Tre fasi di impasto con una lunga lievitazione naturale di oltre 30 ore.<br \/>\n2. Una lenta asciugatura naturale di 12 ore per mantenere inalterati i profumi, i sapori e la morbidezza caratteristici<br \/>\n3. Una lavorazione complessiva di oltre 3 giorni[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;201&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; css=&#8221;.vc_custom_1675934022179{padding-top: 50px !important;padding-bottom: 80px !important;}&#8221; z_index=&#8221;&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Tutti i nostri prodotti sono confezionati singolarmente a mano<\/p>\n<p style=\"text-align: center;\">I nostri prodotti NON contengono conservanti, coloranti, OGM, grassi idrogenati, olio di palma.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 20pt;\"><strong>BONTA&#8217; DI PULA DAL 1967<\/strong><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: 12pt;\">Tutta la bont\u00e0, la fragranza, il gusto ed i profumi del nostro pandoro tradizionale racchiusi in un barattolo di vetro.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\">Il nostro pandoro artigianale in vasocottura si caratterizza per un impasto soffice e morbido, di un colore giallo intenso ed un profumo di uova, burro, vaniglia e zucchero che potrete ritrovare in qualsiasi momento grazie alla tecnica della vasocottura che ne preserva tutte le caratteristiche.<\/span><\/p>\n<p><strong>SENZA <span style=\"font-size: 12pt;\">LATTOSIO<\/span><\/strong><\/p>\n<p>PESO: 200 g<\/p>\n<p><strong>Vendita min. 1 Cartone (6pz per cartone)<\/strong><\/p>\n<p><strong>Indica il numero di cartoni:<\/strong><\/p>\n","protected":false},"featured_media":327,"template":"","meta":[],"product_brand":[],"product_cat":[34,43,18,42],"product_tag":[],"class_list":{"0":"post-318","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-panettoni","7":"product_cat-panettoni-vasocottura","8":"product_cat-senza-lattosio","9":"product_cat-vasocottura","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pandoro in Vasocottura 200 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pandoro in Vasocottura 200 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B\" \/>\n<meta property=\"og:description\" content=\"Tutta la bont\u00e0, la fragranza, il gusto ed i profumi del nostro pandoro tradizionale racchiusi in un barattolo di vetro.  Il nostro pandoro artigianale in vasocottura si caratterizza per un impasto soffice e morbido, di un colore giallo intenso ed un profumo di uova, burro, vaniglia e zucchero che potrete ritrovare in qualsiasi momento grazie alla tecnica della vasocottura che ne preserva tutte le caratteristiche.  SENZA LATTOSIO  PESO: 200 g  Vendita min. 1 Cartone (6pz per cartone)  Indica il numero di cartoni:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/\" \/>\n<meta property=\"og:site_name\" content=\"la Forneria di Pula Shop B2B\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T10:58:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/PANDORO-scaled-e1634400124629.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1479\" \/>\n\t<meta property=\"og:image:height\" content=\"1479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/\",\"name\":\"Pandoro in Vasocottura 200 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B\",\"isPartOf\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/PANDORO-scaled-e1634400124629.jpg\",\"datePublished\":\"2023-05-26T10:15:20+00:00\",\"dateModified\":\"2026-03-05T10:58:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#primaryimage\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/PANDORO-scaled-e1634400124629.jpg\",\"contentUrl\":\"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/PANDORO-scaled-e1634400124629.jpg\",\"width\":1479,\"height\":1479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.laforneria.it\/b2b\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.laforneria.it\/b2b\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pandoro in Vasocottura 200 g &#8211; 1 cartone da 6 Pz &#8211;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.laforneria.it\/b2b\/#website\",\"url\":\"https:\/\/www.laforneria.it\/b2b\/\",\"name\":\"la Forneria di Pula Shop B2B\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.laforneria.it\/b2b\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pandoro in Vasocottura 200 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/","og_locale":"it_IT","og_type":"article","og_title":"Pandoro in Vasocottura 200 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B","og_description":"Tutta la bont\u00e0, la fragranza, il gusto ed i profumi del nostro pandoro tradizionale racchiusi in un barattolo di vetro.  Il nostro pandoro artigianale in vasocottura si caratterizza per un impasto soffice e morbido, di un colore giallo intenso ed un profumo di uova, burro, vaniglia e zucchero che potrete ritrovare in qualsiasi momento grazie alla tecnica della vasocottura che ne preserva tutte le caratteristiche.  SENZA LATTOSIO  PESO: 200 g  Vendita min. 1 Cartone (6pz per cartone)  Indica il numero di cartoni:","og_url":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/","og_site_name":"la Forneria di Pula Shop B2B","article_modified_time":"2026-03-05T10:58:42+00:00","og_image":[{"width":1479,"height":1479,"url":"http:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/PANDORO-scaled-e1634400124629.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/","url":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/","name":"Pandoro in Vasocottura 200 g - 1 cartone da 6 Pz - la Forneria di Pula Shop B2B","isPartOf":{"@id":"https:\/\/www.laforneria.it\/b2b\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#primaryimage"},"image":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/PANDORO-scaled-e1634400124629.jpg","datePublished":"2023-05-26T10:15:20+00:00","dateModified":"2026-03-05T10:58:42+00:00","breadcrumb":{"@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#primaryimage","url":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/PANDORO-scaled-e1634400124629.jpg","contentUrl":"https:\/\/www.laforneria.it\/b2b\/wp-content\/uploads\/2023\/05\/PANDORO-scaled-e1634400124629.jpg","width":1479,"height":1479},{"@type":"BreadcrumbList","@id":"https:\/\/www.laforneria.it\/b2b\/prodotto\/pandoro-tradizionale-in-vasocottura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.laforneria.it\/b2b\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.laforneria.it\/b2b\/negozio\/"},{"@type":"ListItem","position":3,"name":"Pandoro in Vasocottura 200 g &#8211; 1 cartone da 6 Pz &#8211;"}]},{"@type":"WebSite","@id":"https:\/\/www.laforneria.it\/b2b\/#website","url":"https:\/\/www.laforneria.it\/b2b\/","name":"la Forneria di Pula Shop B2B","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laforneria.it\/b2b\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/media\/327"}],"wp:attachment":[{"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_brand?post=318"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_cat?post=318"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.laforneria.it\/b2b\/wp-json\/wp\/v2\/product_tag?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}